{"id":1385,"date":"2025-09-06T14:31:01","date_gmt":"2025-09-06T12:31:01","guid":{"rendered":"https:\/\/riptiderocks.nl\/?post_type=jetpack-portfolio&#038;p=1385"},"modified":"2025-09-14T14:59:43","modified_gmt":"2025-09-14T12:59:43","slug":"cafe-maneslust-6-9-2025","status":"publish","type":"jetpack-portfolio","link":"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/","title":{"rendered":"Caf\u00e9 Maneslust 6-9-2025"},"content":{"rendered":"\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:66.78799%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1386\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4202\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4202.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4202\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4202.jpg?fit=700%2C467&amp;ssl=1\" data-attachment-id=\"1386\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4202\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4202.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4202\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4202.jpg?fit=700%2C467&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 1 of 16 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4202-1024x683.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4202-1024x683.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4202-1024x683.jpg?strip=info&#038;w=1200 1200w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4202-1024x683.jpg?strip=info&#038;w=1500 1500w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4202-1024x683.jpg?strip=info&#038;w=1795 1795w\" alt=\"\" data-height=\"1197\" data-id=\"1386\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1386\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4202-1024x683.jpg\" data-width=\"1795\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4202-1024x683.jpg\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.21201%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1387\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4205\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4205.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4205\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4205.jpg?fit=700%2C467&amp;ssl=1\" data-attachment-id=\"1387\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4205\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4205.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4205\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4205.jpg?fit=700%2C467&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 2 of 16 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4205-1024x683.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4205-1024x683.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4205-1024x683.jpg?strip=info&#038;w=1200 1200w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4205-1024x683.jpg?strip=info&#038;w=1500 1500w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4205-1024x683.jpg?strip=info&#038;w=1795 1795w\" alt=\"\" data-height=\"1197\" data-id=\"1387\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1387\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4205-1024x683.jpg\" data-width=\"1795\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4205-1024x683.jpg\" data-amp-layout=\"responsive\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1388\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4212\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4212.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4212\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4212.jpg?fit=700%2C467&amp;ssl=1\" data-attachment-id=\"1388\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4212\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4212.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4212\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4212.jpg?fit=700%2C467&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 3 of 16 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4212-1024x683.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4212-1024x683.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4212-1024x683.jpg?strip=info&#038;w=1200 1200w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4212-1024x683.jpg?strip=info&#038;w=1500 1500w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4212-1024x683.jpg?strip=info&#038;w=1795 1795w\" alt=\"\" data-height=\"1197\" data-id=\"1388\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1388\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4212-1024x683.jpg\" data-width=\"1795\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4212-1024x683.jpg\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:52.73761%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1389\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4255\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4255.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4255\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4255.jpg?fit=700%2C467&amp;ssl=1\" data-attachment-id=\"1389\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4255\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4255.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4255\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4255.jpg?fit=700%2C467&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 4 of 16 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4255-1024x683.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4255-1024x683.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4255-1024x683.jpg?strip=info&#038;w=1200 1200w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4255-1024x683.jpg?strip=info&#038;w=1500 1500w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4255-1024x683.jpg?strip=info&#038;w=1795 1795w\" alt=\"\" data-height=\"1197\" data-id=\"1389\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1389\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4255-1024x683.jpg\" data-width=\"1795\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4255-1024x683.jpg\" data-amp-layout=\"responsive\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1390\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4266\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4266.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4266\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4266.jpg?fit=700%2C467&amp;ssl=1\" data-attachment-id=\"1390\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4266\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4266.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4266\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4266.jpg?fit=700%2C467&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 5 of 16 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4266-1024x683.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4266-1024x683.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4266-1024x683.jpg?strip=info&#038;w=1200 1200w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4266-1024x683.jpg?strip=info&#038;w=1500 1500w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4266-1024x683.jpg?strip=info&#038;w=1795 1795w\" alt=\"\" data-height=\"1197\" data-id=\"1390\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1390\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4266-1024x683.jpg\" data-width=\"1795\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4266-1024x683.jpg\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:47.26239%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1391\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4270\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4270.jpg?fit=1197%2C1795&amp;ssl=1\" data-orig-size=\"1197,1795\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4270\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4270.jpg?fit=683%2C1024&amp;ssl=1\" data-attachment-id=\"1391\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4270\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4270.jpg?fit=1197%2C1795&amp;ssl=1\" data-orig-size=\"1197,1795\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4270\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4270.jpg?fit=683%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 6 of 16 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4270-683x1024.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4270-683x1024.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4270-683x1024.jpg?strip=info&#038;w=1197 1197w\" alt=\"\" data-height=\"1795\" data-id=\"1391\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1391\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4270-683x1024.jpg\" data-width=\"1197\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4270-683x1024.jpg\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:57.38033%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1392\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4276\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4276.jpg?fit=1197%2C1795&amp;ssl=1\" data-orig-size=\"1197,1795\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4276\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4276.jpg?fit=683%2C1024&amp;ssl=1\" data-attachment-id=\"1392\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4276\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4276.jpg?fit=1197%2C1795&amp;ssl=1\" data-orig-size=\"1197,1795\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4276\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4276.jpg?fit=683%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 7 of 16 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4276-683x1024.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4276-683x1024.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4276-683x1024.jpg?strip=info&#038;w=1197 1197w\" alt=\"\" data-height=\"1795\" data-id=\"1392\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1392\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4276-683x1024.jpg\" data-width=\"1197\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4276-683x1024.jpg\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:42.61967%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1393\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4278\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4278\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?fit=700%2C467&amp;ssl=1\" data-attachment-id=\"1393\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4278\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4278\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?fit=700%2C467&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 8 of 16 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278-1024x683.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278-1024x683.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278-1024x683.jpg?strip=info&#038;w=1200 1200w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278-1024x683.jpg?strip=info&#038;w=1500 1500w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278-1024x683.jpg?strip=info&#038;w=1795 1795w\" alt=\"\" data-height=\"1197\" data-id=\"1393\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1393\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278-1024x683.jpg\" data-width=\"1795\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278-1024x683.jpg\" data-amp-layout=\"responsive\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1394\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4279\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4279.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4279\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4279.jpg?fit=700%2C467&amp;ssl=1\" data-attachment-id=\"1394\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4279\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4279.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4279\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4279.jpg?fit=700%2C467&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 9 of 16 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4279-1024x683.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4279-1024x683.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4279-1024x683.jpg?strip=info&#038;w=1200 1200w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4279-1024x683.jpg?strip=info&#038;w=1500 1500w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4279-1024x683.jpg?strip=info&#038;w=1795 1795w\" alt=\"\" data-height=\"1197\" data-id=\"1394\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1394\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4279-1024x683.jpg\" data-width=\"1795\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4279-1024x683.jpg\" data-amp-layout=\"responsive\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1395\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4303\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4303.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4303\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4303.jpg?fit=700%2C467&amp;ssl=1\" data-attachment-id=\"1395\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4303\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4303.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4303\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4303.jpg?fit=700%2C467&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 10 of 16 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4303-1024x683.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4303-1024x683.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4303-1024x683.jpg?strip=info&#038;w=1200 1200w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4303-1024x683.jpg?strip=info&#038;w=1500 1500w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4303-1024x683.jpg?strip=info&#038;w=1795 1795w\" alt=\"\" data-height=\"1197\" data-id=\"1395\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1395\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4303-1024x683.jpg\" data-width=\"1795\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4303-1024x683.jpg\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:69.16837%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1396\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4314\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4314.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4314\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4314.jpg?fit=700%2C467&amp;ssl=1\" data-attachment-id=\"1396\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4314\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4314.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4314\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4314.jpg?fit=700%2C467&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 11 of 16 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4314-1024x683.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4314-1024x683.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4314-1024x683.jpg?strip=info&#038;w=1200 1200w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4314-1024x683.jpg?strip=info&#038;w=1500 1500w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4314-1024x683.jpg?strip=info&#038;w=1795 1795w\" alt=\"\" data-height=\"1197\" data-id=\"1396\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1396\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4314-1024x683.jpg\" data-width=\"1795\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4314-1024x683.jpg\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:30.83163%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1397\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4377\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4377.jpg?fit=1197%2C1795&amp;ssl=1\" data-orig-size=\"1197,1795\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4377\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4377.jpg?fit=683%2C1024&amp;ssl=1\" data-attachment-id=\"1397\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4377\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4377.jpg?fit=1197%2C1795&amp;ssl=1\" data-orig-size=\"1197,1795\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4377\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4377.jpg?fit=683%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 12 of 16 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4377-683x1024.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4377-683x1024.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4377-683x1024.jpg?strip=info&#038;w=1197 1197w\" alt=\"\" data-height=\"1795\" data-id=\"1397\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1397\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4377-683x1024.jpg\" data-width=\"1197\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4377-683x1024.jpg\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:19.07793%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1398\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4390\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4390.jpg?fit=1197%2C1795&amp;ssl=1\" data-orig-size=\"1197,1795\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4390\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4390.jpg?fit=683%2C1024&amp;ssl=1\" data-attachment-id=\"1398\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4390\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4390.jpg?fit=1197%2C1795&amp;ssl=1\" data-orig-size=\"1197,1795\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4390\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4390.jpg?fit=683%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 13 of 16 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4390-683x1024.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4390-683x1024.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4390-683x1024.jpg?strip=info&#038;w=1197 1197w\" alt=\"\" data-height=\"1795\" data-id=\"1398\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1398\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4390-683x1024.jpg\" data-width=\"1197\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4390-683x1024.jpg\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:19.07793%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1399\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4412\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4412.jpg?fit=1197%2C1795&amp;ssl=1\" data-orig-size=\"1197,1795\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4412\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4412.jpg?fit=683%2C1024&amp;ssl=1\" data-attachment-id=\"1399\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4412\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4412.jpg?fit=1197%2C1795&amp;ssl=1\" data-orig-size=\"1197,1795\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4412\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4412.jpg?fit=683%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 14 of 16 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4412-683x1024.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4412-683x1024.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4412-683x1024.jpg?strip=info&#038;w=1197 1197w\" alt=\"\" data-height=\"1795\" data-id=\"1399\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1399\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4412-683x1024.jpg\" data-width=\"1197\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4412-683x1024.jpg\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:42.76621%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1400\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4440\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4440.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4440\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4440.jpg?fit=700%2C467&amp;ssl=1\" data-attachment-id=\"1400\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4440\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4440.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4440\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4440.jpg?fit=700%2C467&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 15 of 16 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4440-1024x683.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4440-1024x683.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4440-1024x683.jpg?strip=info&#038;w=1200 1200w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4440-1024x683.jpg?strip=info&#038;w=1500 1500w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4440-1024x683.jpg?strip=info&#038;w=1795 1795w\" alt=\"\" data-height=\"1197\" data-id=\"1400\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1400\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4440-1024x683.jpg\" data-width=\"1795\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4440-1024x683.jpg\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:19.07793%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1401\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4450\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4450.jpg?fit=1197%2C1795&amp;ssl=1\" data-orig-size=\"1197,1795\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4450\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4450.jpg?fit=683%2C1024&amp;ssl=1\" data-attachment-id=\"1401\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4450\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4450.jpg?fit=1197%2C1795&amp;ssl=1\" data-orig-size=\"1197,1795\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4450\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4450.jpg?fit=683%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 16 of 16 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4450-683x1024.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4450-683x1024.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4450-683x1024.jpg?strip=info&#038;w=1197 1197w\" alt=\"\" data-height=\"1795\" data-id=\"1401\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1401\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4450-683x1024.jpg\" data-width=\"1197\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4450-683x1024.jpg\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><\/div><\/div><\/div>\n\n\n<figure class=\"wp-block-post-featured-image\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?resize=700%2C467&#038;ssl=1\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" style=\"object-fit:cover;\" srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?w=1795&amp;ssl=1 1795w, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?resize=1024%2C683&amp;ssl=1 1024w, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?resize=700%2C467&amp;ssl=1 700w, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?resize=900%2C600&amp;ssl=1 900w, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?resize=600%2C400&amp;ssl=1 600w, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?w=1400 1400w\" sizes=\"(max-width: 700px) 100vw, 700px\" data-attachment-id=\"1393\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/gro-1w2a4278\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?fit=1795%2C1197&amp;ssl=1\" data-orig-size=\"1795,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"GRo-1W2A4278\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?fit=700%2C467&amp;ssl=1\" \/><\/figure>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1393,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"jetpack-portfolio-type":[],"jetpack-portfolio-tag":[],"class_list":["post-1385","jetpack-portfolio","type-jetpack-portfolio","status-publish","format-standard","has-post-thumbnail","hentry"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":1212,"url":"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-the-groove-sittard-5-4-2025\/","url_meta":{"origin":1385,"position":0},"title":"Caf\u00e9 The Groove Sittard 5-4-2025","author":"Riptiderocks","date":"8 april, 2025","format":false,"excerpt":"","rel":"","context":"Soortgelijk bericht","block_context":{"text":"Soortgelijk bericht","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/489284582_1194080382718048_7389646420476220897_n.jpg?fit=1200%2C960&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/489284582_1194080382718048_7389646420476220897_n.jpg?fit=1200%2C960&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/489284582_1194080382718048_7389646420476220897_n.jpg?fit=1200%2C960&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/489284582_1194080382718048_7389646420476220897_n.jpg?fit=1200%2C960&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/489284582_1194080382718048_7389646420476220897_n.jpg?fit=1200%2C960&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1323,"url":"https:\/\/riptiderocks.nl\/index.php\/portfolio\/fraiche-open-air-6-7-2025\/","url_meta":{"origin":1385,"position":1},"title":"Fraiche Open Air 6-7-2025","author":"Riptiderocks","date":"6 juli, 2025","format":false,"excerpt":"","rel":"","context":"Soortgelijk bericht","block_context":{"text":"Soortgelijk bericht","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/theband.jpg?fit=1200%2C791&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/theband.jpg?fit=1200%2C791&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/theband.jpg?fit=1200%2C791&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/theband.jpg?fit=1200%2C791&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/theband.jpg?fit=1200%2C791&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1290,"url":"https:\/\/riptiderocks.nl\/index.php\/portfolio\/rockfabrik-open-air-2025\/","url_meta":{"origin":1385,"position":2},"title":"Rockfabrik Open Air 2025 5-9-2025","author":"Riptiderocks","date":"5 september, 2025","format":false,"excerpt":"","rel":"","context":"Soortgelijk bericht","block_context":{"text":"Soortgelijk bericht","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/544775552_1187926869810057_6712249075739597564_n.jpg?fit=1200%2C804&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/544775552_1187926869810057_6712249075739597564_n.jpg?fit=1200%2C804&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/544775552_1187926869810057_6712249075739597564_n.jpg?fit=1200%2C804&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/544775552_1187926869810057_6712249075739597564_n.jpg?fit=1200%2C804&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/544775552_1187926869810057_6712249075739597564_n.jpg?fit=1200%2C804&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1116,"url":"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-the-groove-sittard-14-05-2022\/","url_meta":{"origin":1385,"position":3},"title":"Caf\u00e9 The Groove Sittard 14-05-2022","author":"Riptiderocks","date":"18 mei, 2022","format":false,"excerpt":"","rel":"","context":"Soortgelijk bericht","block_context":{"text":"Soortgelijk bericht","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2022\/05\/Y8B1123.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2022\/05\/Y8B1123.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2022\/05\/Y8B1123.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2022\/05\/Y8B1123.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2022\/05\/Y8B1123.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1244,"url":"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/","url_meta":{"origin":1385,"position":4},"title":"Bands for Love Landgraaf 29-3-2025","author":"Riptiderocks","date":"1 april, 2025","format":false,"excerpt":"","rel":"","context":"Soortgelijk bericht","block_context":{"text":"Soortgelijk bericht","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":769,"url":"https:\/\/riptiderocks.nl\/index.php\/portfolio\/friends-family-try-out-oefenbunker-landgraaf-9-12-2017\/","url_meta":{"origin":1385,"position":5},"title":"FRIENDS &#038; FAMILY TRY-OUT OEFENBUNKER LANDGRAAF 9-12-2017","author":"Riptiderocks","date":"12 september, 2016","format":false,"excerpt":"","rel":"","context":"Soortgelijk bericht","block_context":{"text":"Soortgelijk bericht","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b5647.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b5647.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b5647.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b5647.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b5647.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/jetpack-portfolio\/1385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/jetpack-portfolio"}],"about":[{"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/types\/jetpack-portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/comments?post=1385"}],"version-history":[{"count":2,"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/jetpack-portfolio\/1385\/revisions"}],"predecessor-version":[{"id":1442,"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/jetpack-portfolio\/1385\/revisions\/1442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/media\/1393"}],"wp:attachment":[{"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/media?parent=1385"}],"wp:term":[{"taxonomy":"jetpack-portfolio-type","embeddable":true,"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/jetpack-portfolio-type?post=1385"},{"taxonomy":"jetpack-portfolio-tag","embeddable":true,"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/jetpack-portfolio-tag?post=1385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}