{"id":1244,"date":"2025-04-01T19:46:47","date_gmt":"2025-04-01T17:46:47","guid":{"rendered":"https:\/\/riptiderocks.nl\/?post_type=jetpack-portfolio&#038;p=1244"},"modified":"2025-04-08T19:57:57","modified_gmt":"2025-04-08T17:57:57","slug":"bands-for-love-landgraaf-29-3-2025","status":"publish","type":"jetpack-portfolio","link":"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/","title":{"rendered":"Bands for Love Landgraaf 29-3-2025"},"content":{"rendered":"\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:42.79451%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1246\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487897119_1188148739977879_8565325405042328976_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487897119_1188148739977879_8565325405042328976_n-1.jpg?fit=1796%2C1197&amp;ssl=1\" data-orig-size=\"1796,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487897119_1188148739977879_8565325405042328976_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487897119_1188148739977879_8565325405042328976_n-1.jpg?fit=700%2C466&amp;ssl=1\" data-attachment-id=\"1246\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487897119_1188148739977879_8565325405042328976_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487897119_1188148739977879_8565325405042328976_n-1.jpg?fit=1796%2C1197&amp;ssl=1\" data-orig-size=\"1796,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487897119_1188148739977879_8565325405042328976_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487897119_1188148739977879_8565325405042328976_n-1.jpg?fit=700%2C466&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 1 of 14 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487897119_1188148739977879_8565325405042328976_n-1-1024x682.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487897119_1188148739977879_8565325405042328976_n-1-1024x682.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487897119_1188148739977879_8565325405042328976_n-1-1024x682.jpg?strip=info&#038;w=1200 1200w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487897119_1188148739977879_8565325405042328976_n-1-1024x682.jpg?strip=info&#038;w=1500 1500w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487897119_1188148739977879_8565325405042328976_n-1-1024x682.jpg?strip=info&#038;w=1796 1796w\" alt=\"\" data-height=\"1197\" data-id=\"1246\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1246\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487897119_1188148739977879_8565325405042328976_n-1-1024x682.jpg\" data-width=\"1796\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487897119_1188148739977879_8565325405042328976_n-1-1024x682.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Afbeelding 1 of 14 op volledig scherm openen\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:19.06850%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1247\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487818257_1188148466644573_3345439988906866975_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487818257_1188148466644573_3345439988906866975_n-1.jpg?fit=1197%2C1796&amp;ssl=1\" data-orig-size=\"1197,1796\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487818257_1188148466644573_3345439988906866975_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487818257_1188148466644573_3345439988906866975_n-1.jpg?fit=682%2C1024&amp;ssl=1\" data-attachment-id=\"1247\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487818257_1188148466644573_3345439988906866975_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487818257_1188148466644573_3345439988906866975_n-1.jpg?fit=1197%2C1796&amp;ssl=1\" data-orig-size=\"1197,1796\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487818257_1188148466644573_3345439988906866975_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487818257_1188148466644573_3345439988906866975_n-1.jpg?fit=682%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 2 of 14 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487818257_1188148466644573_3345439988906866975_n-1-682x1024.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487818257_1188148466644573_3345439988906866975_n-1-682x1024.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487818257_1188148466644573_3345439988906866975_n-1-682x1024.jpg?strip=info&#038;w=1197 1197w\" alt=\"\" data-height=\"1796\" data-id=\"1247\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1247\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487818257_1188148466644573_3345439988906866975_n-1-682x1024.jpg\" data-width=\"1197\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487818257_1188148466644573_3345439988906866975_n-1-682x1024.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Afbeelding 2 of 14 op volledig scherm openen\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:19.06850%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1248\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487962780_1188148473311239_1171397225353154748_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487962780_1188148473311239_1171397225353154748_n-1.jpg?fit=1197%2C1796&amp;ssl=1\" data-orig-size=\"1197,1796\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487962780_1188148473311239_1171397225353154748_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487962780_1188148473311239_1171397225353154748_n-1.jpg?fit=682%2C1024&amp;ssl=1\" data-attachment-id=\"1248\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487962780_1188148473311239_1171397225353154748_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487962780_1188148473311239_1171397225353154748_n-1.jpg?fit=1197%2C1796&amp;ssl=1\" data-orig-size=\"1197,1796\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487962780_1188148473311239_1171397225353154748_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487962780_1188148473311239_1171397225353154748_n-1.jpg?fit=682%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 3 of 14 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487962780_1188148473311239_1171397225353154748_n-1-682x1024.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487962780_1188148473311239_1171397225353154748_n-1-682x1024.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487962780_1188148473311239_1171397225353154748_n-1-682x1024.jpg?strip=info&#038;w=1197 1197w\" alt=\"\" data-height=\"1796\" data-id=\"1248\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1248\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487962780_1188148473311239_1171397225353154748_n-1-682x1024.jpg\" data-width=\"1197\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487962780_1188148473311239_1171397225353154748_n-1-682x1024.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Afbeelding 3 of 14 op volledig scherm openen\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:19.06850%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1249\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487832486_1188148523311234_3472914272885931485_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487832486_1188148523311234_3472914272885931485_n-1.jpg?fit=1197%2C1796&amp;ssl=1\" data-orig-size=\"1197,1796\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487832486_1188148523311234_3472914272885931485_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487832486_1188148523311234_3472914272885931485_n-1.jpg?fit=682%2C1024&amp;ssl=1\" data-attachment-id=\"1249\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487832486_1188148523311234_3472914272885931485_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487832486_1188148523311234_3472914272885931485_n-1.jpg?fit=1197%2C1796&amp;ssl=1\" data-orig-size=\"1197,1796\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487832486_1188148523311234_3472914272885931485_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487832486_1188148523311234_3472914272885931485_n-1.jpg?fit=682%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 4 of 14 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487832486_1188148523311234_3472914272885931485_n-1-682x1024.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487832486_1188148523311234_3472914272885931485_n-1-682x1024.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487832486_1188148523311234_3472914272885931485_n-1-682x1024.jpg?strip=info&#038;w=1197 1197w\" alt=\"\" data-height=\"1796\" data-id=\"1249\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1249\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487832486_1188148523311234_3472914272885931485_n-1-682x1024.jpg\" data-width=\"1197\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487832486_1188148523311234_3472914272885931485_n-1-682x1024.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Afbeelding 4 of 14 op volledig scherm openen\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1250\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/488366200_1188148529977900_8694267970351818836_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488366200_1188148529977900_8694267970351818836_n-1.jpg?fit=1197%2C1796&amp;ssl=1\" data-orig-size=\"1197,1796\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"488366200_1188148529977900_8694267970351818836_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488366200_1188148529977900_8694267970351818836_n-1.jpg?fit=682%2C1024&amp;ssl=1\" data-attachment-id=\"1250\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/488366200_1188148529977900_8694267970351818836_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488366200_1188148529977900_8694267970351818836_n-1.jpg?fit=1197%2C1796&amp;ssl=1\" data-orig-size=\"1197,1796\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"488366200_1188148529977900_8694267970351818836_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488366200_1188148529977900_8694267970351818836_n-1.jpg?fit=682%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 5 of 14 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488366200_1188148529977900_8694267970351818836_n-1-682x1024.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488366200_1188148529977900_8694267970351818836_n-1-682x1024.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488366200_1188148529977900_8694267970351818836_n-1-682x1024.jpg?strip=info&#038;w=1197 1197w\" alt=\"\" data-height=\"1796\" data-id=\"1250\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1250\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488366200_1188148529977900_8694267970351818836_n-1-682x1024.jpg\" data-width=\"1197\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488366200_1188148529977900_8694267970351818836_n-1-682x1024.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Afbeelding 5 of 14 op volledig scherm openen\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1251\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487811950_1188148553311231_45422875819252023_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487811950_1188148553311231_45422875819252023_n-1.jpg?fit=1197%2C1796&amp;ssl=1\" data-orig-size=\"1197,1796\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487811950_1188148553311231_45422875819252023_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487811950_1188148553311231_45422875819252023_n-1.jpg?fit=682%2C1024&amp;ssl=1\" data-attachment-id=\"1251\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487811950_1188148553311231_45422875819252023_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487811950_1188148553311231_45422875819252023_n-1.jpg?fit=1197%2C1796&amp;ssl=1\" data-orig-size=\"1197,1796\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487811950_1188148553311231_45422875819252023_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487811950_1188148553311231_45422875819252023_n-1.jpg?fit=682%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 6 of 14 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487811950_1188148553311231_45422875819252023_n-1-682x1024.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487811950_1188148553311231_45422875819252023_n-1-682x1024.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487811950_1188148553311231_45422875819252023_n-1-682x1024.jpg?strip=info&#038;w=1197 1197w\" alt=\"\" data-height=\"1796\" data-id=\"1251\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1251\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487811950_1188148553311231_45422875819252023_n-1-682x1024.jpg\" data-width=\"1197\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487811950_1188148553311231_45422875819252023_n-1-682x1024.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Afbeelding 6 of 14 op volledig scherm openen\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:52.76611%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1252\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487768644_1188148559977897_8219634722779160876_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768644_1188148559977897_8219634722779160876_n-1.jpg?fit=1796%2C1197&amp;ssl=1\" data-orig-size=\"1796,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487768644_1188148559977897_8219634722779160876_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768644_1188148559977897_8219634722779160876_n-1.jpg?fit=700%2C466&amp;ssl=1\" data-attachment-id=\"1252\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487768644_1188148559977897_8219634722779160876_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768644_1188148559977897_8219634722779160876_n-1.jpg?fit=1796%2C1197&amp;ssl=1\" data-orig-size=\"1796,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487768644_1188148559977897_8219634722779160876_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768644_1188148559977897_8219634722779160876_n-1.jpg?fit=700%2C466&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 7 of 14 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768644_1188148559977897_8219634722779160876_n-1-1024x682.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768644_1188148559977897_8219634722779160876_n-1-1024x682.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768644_1188148559977897_8219634722779160876_n-1-1024x682.jpg?strip=info&#038;w=1200 1200w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768644_1188148559977897_8219634722779160876_n-1-1024x682.jpg?strip=info&#038;w=1500 1500w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768644_1188148559977897_8219634722779160876_n-1-1024x682.jpg?strip=info&#038;w=1796 1796w\" alt=\"\" data-height=\"1197\" data-id=\"1252\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1252\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768644_1188148559977897_8219634722779160876_n-1-1024x682.jpg\" data-width=\"1796\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768644_1188148559977897_8219634722779160876_n-1-1024x682.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Afbeelding 7 of 14 op volledig scherm openen\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1253\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487978470_1188148603311226_5515689396966221031_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487978470_1188148603311226_5515689396966221031_n-1.jpg?fit=1796%2C1197&amp;ssl=1\" data-orig-size=\"1796,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487978470_1188148603311226_5515689396966221031_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487978470_1188148603311226_5515689396966221031_n-1.jpg?fit=700%2C466&amp;ssl=1\" data-attachment-id=\"1253\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487978470_1188148603311226_5515689396966221031_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487978470_1188148603311226_5515689396966221031_n-1.jpg?fit=1796%2C1197&amp;ssl=1\" data-orig-size=\"1796,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487978470_1188148603311226_5515689396966221031_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487978470_1188148603311226_5515689396966221031_n-1.jpg?fit=700%2C466&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 8 of 14 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487978470_1188148603311226_5515689396966221031_n-1-1024x682.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487978470_1188148603311226_5515689396966221031_n-1-1024x682.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487978470_1188148603311226_5515689396966221031_n-1-1024x682.jpg?strip=info&#038;w=1200 1200w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487978470_1188148603311226_5515689396966221031_n-1-1024x682.jpg?strip=info&#038;w=1500 1500w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487978470_1188148603311226_5515689396966221031_n-1-1024x682.jpg?strip=info&#038;w=1796 1796w\" alt=\"\" data-height=\"1197\" data-id=\"1253\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1253\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487978470_1188148603311226_5515689396966221031_n-1-1024x682.jpg\" data-width=\"1796\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487978470_1188148603311226_5515689396966221031_n-1-1024x682.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Afbeelding 8 of 14 op volledig scherm openen\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:47.23389%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1254\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487768641_1188148609977892_1539240350458907880_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768641_1188148609977892_1539240350458907880_n-1.jpg?fit=1197%2C1796&amp;ssl=1\" data-orig-size=\"1197,1796\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487768641_1188148609977892_1539240350458907880_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768641_1188148609977892_1539240350458907880_n-1.jpg?fit=682%2C1024&amp;ssl=1\" data-attachment-id=\"1254\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487768641_1188148609977892_1539240350458907880_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768641_1188148609977892_1539240350458907880_n-1.jpg?fit=1197%2C1796&amp;ssl=1\" data-orig-size=\"1197,1796\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487768641_1188148609977892_1539240350458907880_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768641_1188148609977892_1539240350458907880_n-1.jpg?fit=682%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 9 of 14 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768641_1188148609977892_1539240350458907880_n-1-682x1024.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768641_1188148609977892_1539240350458907880_n-1-682x1024.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768641_1188148609977892_1539240350458907880_n-1-682x1024.jpg?strip=info&#038;w=1197 1197w\" alt=\"\" data-height=\"1796\" data-id=\"1254\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1254\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768641_1188148609977892_1539240350458907880_n-1-682x1024.jpg\" data-width=\"1197\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487768641_1188148609977892_1539240350458907880_n-1-682x1024.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Afbeelding 9 of 14 op volledig scherm openen\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:42.64783%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1255\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487822887_1188148659977887_5488042316419300080_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487822887_1188148659977887_5488042316419300080_n-1.jpg?fit=1796%2C1197&amp;ssl=1\" data-orig-size=\"1796,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487822887_1188148659977887_5488042316419300080_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487822887_1188148659977887_5488042316419300080_n-1.jpg?fit=700%2C466&amp;ssl=1\" data-attachment-id=\"1255\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487822887_1188148659977887_5488042316419300080_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487822887_1188148659977887_5488042316419300080_n-1.jpg?fit=1796%2C1197&amp;ssl=1\" data-orig-size=\"1796,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487822887_1188148659977887_5488042316419300080_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487822887_1188148659977887_5488042316419300080_n-1.jpg?fit=700%2C466&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 10 of 14 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487822887_1188148659977887_5488042316419300080_n-1-1024x682.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487822887_1188148659977887_5488042316419300080_n-1-1024x682.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487822887_1188148659977887_5488042316419300080_n-1-1024x682.jpg?strip=info&#038;w=1200 1200w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487822887_1188148659977887_5488042316419300080_n-1-1024x682.jpg?strip=info&#038;w=1500 1500w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487822887_1188148659977887_5488042316419300080_n-1-1024x682.jpg?strip=info&#038;w=1796 1796w\" alt=\"\" data-height=\"1197\" data-id=\"1255\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1255\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487822887_1188148659977887_5488042316419300080_n-1-1024x682.jpg\" data-width=\"1796\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487822887_1188148659977887_5488042316419300080_n-1-1024x682.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Afbeelding 10 of 14 op volledig scherm openen\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1256\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/488002652_1188148666644553_6816874528129596959_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488002652_1188148666644553_6816874528129596959_n-1.jpg?fit=1796%2C1197&amp;ssl=1\" data-orig-size=\"1796,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"488002652_1188148666644553_6816874528129596959_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488002652_1188148666644553_6816874528129596959_n-1.jpg?fit=700%2C466&amp;ssl=1\" data-attachment-id=\"1256\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/488002652_1188148666644553_6816874528129596959_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488002652_1188148666644553_6816874528129596959_n-1.jpg?fit=1796%2C1197&amp;ssl=1\" data-orig-size=\"1796,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"488002652_1188148666644553_6816874528129596959_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488002652_1188148666644553_6816874528129596959_n-1.jpg?fit=700%2C466&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 11 of 14 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488002652_1188148666644553_6816874528129596959_n-1-1024x682.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488002652_1188148666644553_6816874528129596959_n-1-1024x682.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488002652_1188148666644553_6816874528129596959_n-1-1024x682.jpg?strip=info&#038;w=1200 1200w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488002652_1188148666644553_6816874528129596959_n-1-1024x682.jpg?strip=info&#038;w=1500 1500w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488002652_1188148666644553_6816874528129596959_n-1-1024x682.jpg?strip=info&#038;w=1796 1796w\" alt=\"\" data-height=\"1197\" data-id=\"1256\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1256\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488002652_1188148666644553_6816874528129596959_n-1-1024x682.jpg\" data-width=\"1796\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488002652_1188148666644553_6816874528129596959_n-1-1024x682.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Afbeelding 11 of 14 op volledig scherm openen\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1257\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/488265114_1188148686644551_357426418033658158_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488265114_1188148686644551_357426418033658158_n-1.jpg?fit=1796%2C1197&amp;ssl=1\" data-orig-size=\"1796,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"488265114_1188148686644551_357426418033658158_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488265114_1188148686644551_357426418033658158_n-1.jpg?fit=700%2C466&amp;ssl=1\" data-attachment-id=\"1257\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/488265114_1188148686644551_357426418033658158_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488265114_1188148686644551_357426418033658158_n-1.jpg?fit=1796%2C1197&amp;ssl=1\" data-orig-size=\"1796,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"488265114_1188148686644551_357426418033658158_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488265114_1188148686644551_357426418033658158_n-1.jpg?fit=700%2C466&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 12 of 14 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488265114_1188148686644551_357426418033658158_n-1-1024x682.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488265114_1188148686644551_357426418033658158_n-1-1024x682.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488265114_1188148686644551_357426418033658158_n-1-1024x682.jpg?strip=info&#038;w=1200 1200w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488265114_1188148686644551_357426418033658158_n-1-1024x682.jpg?strip=info&#038;w=1500 1500w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488265114_1188148686644551_357426418033658158_n-1-1024x682.jpg?strip=info&#038;w=1796 1796w\" alt=\"\" data-height=\"1197\" data-id=\"1257\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1257\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488265114_1188148686644551_357426418033658158_n-1-1024x682.jpg\" data-width=\"1796\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/488265114_1188148686644551_357426418033658158_n-1-1024x682.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Afbeelding 12 of 14 op volledig scherm openen\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:57.35217%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1258\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487943496_1188148696644550_2867899726351736991_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487943496_1188148696644550_2867899726351736991_n-1.jpg?fit=1197%2C1796&amp;ssl=1\" data-orig-size=\"1197,1796\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487943496_1188148696644550_2867899726351736991_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487943496_1188148696644550_2867899726351736991_n-1.jpg?fit=682%2C1024&amp;ssl=1\" data-attachment-id=\"1258\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487943496_1188148696644550_2867899726351736991_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487943496_1188148696644550_2867899726351736991_n-1.jpg?fit=1197%2C1796&amp;ssl=1\" data-orig-size=\"1197,1796\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487943496_1188148696644550_2867899726351736991_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487943496_1188148696644550_2867899726351736991_n-1.jpg?fit=682%2C1024&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 13 of 14 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487943496_1188148696644550_2867899726351736991_n-1-682x1024.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487943496_1188148696644550_2867899726351736991_n-1-682x1024.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487943496_1188148696644550_2867899726351736991_n-1-682x1024.jpg?strip=info&#038;w=1197 1197w\" alt=\"\" data-height=\"1796\" data-id=\"1258\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1258\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487943496_1188148696644550_2867899726351736991_n-1-682x1024.jpg\" data-width=\"1197\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487943496_1188148696644550_2867899726351736991_n-1-682x1024.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Afbeelding 13 of 14 op volledig scherm openen\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:100.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"1259\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487944374_1188148719977881_3152174232540406055_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n-1.jpg?fit=1796%2C1197&amp;ssl=1\" data-orig-size=\"1796,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487944374_1188148719977881_3152174232540406055_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n-1.jpg?fit=700%2C466&amp;ssl=1\" data-attachment-id=\"1259\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/bands-for-love-landgraaf-29-3-2025\/487944374_1188148719977881_3152174232540406055_n-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n-1.jpg?fit=1796%2C1197&amp;ssl=1\" data-orig-size=\"1796,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487944374_1188148719977881_3152174232540406055_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n-1.jpg?fit=700%2C466&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Afbeelding 14 of 14 op volledig scherm openen\"srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n-1-1024x682.jpg?strip=info&#038;w=600 600w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n-1-1024x682.jpg?strip=info&#038;w=900 900w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n-1-1024x682.jpg?strip=info&#038;w=1200 1200w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n-1-1024x682.jpg?strip=info&#038;w=1500 1500w,https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n-1-1024x682.jpg?strip=info&#038;w=1796 1796w\" alt=\"\" data-height=\"1197\" data-id=\"1259\" data-link=\"https:\/\/riptiderocks.nl\/?attachment_id=1259\" data-url=\"http:\/\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n-1-1024x682.jpg\" data-width=\"1796\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n-1-1024x682.jpg\" data-amp-layout=\"responsive\" tabindex=\"0\" role=\"button\" aria-label=\"Afbeelding 14 of 14 op volledig scherm openen\"\/><\/figure><\/div><\/div><\/div><\/div><\/div>\n\n\n<figure class=\"wp-block-post-featured-image\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n.jpg?resize=700%2C467&#038;ssl=1\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" style=\"object-fit:cover;\" srcset=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n.jpg?w=1796&amp;ssl=1 1796w, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n.jpg?resize=1024%2C682&amp;ssl=1 1024w, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n.jpg?resize=768%2C512&amp;ssl=1 768w, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n.jpg?resize=1536%2C1024&amp;ssl=1 1536w, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n.jpg?resize=700%2C467&amp;ssl=1 700w, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n.jpg?resize=900%2C600&amp;ssl=1 900w, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n.jpg?resize=600%2C400&amp;ssl=1 600w, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n.jpg?w=1400 1400w\" sizes=\"(max-width: 700px) 100vw, 700px\" data-attachment-id=\"1236\" data-permalink=\"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-the-groove-sittard-5-4-2025\/487944374_1188148719977881_3152174232540406055_n\/\" data-orig-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n.jpg?fit=1796%2C1197&amp;ssl=1\" data-orig-size=\"1796,1197\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;Giel Robeerst&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"487944374_1188148719977881_3152174232540406055_n\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/487944374_1188148719977881_3152174232540406055_n.jpg?fit=700%2C466&amp;ssl=1\" \/><\/figure>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1236,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"jetpack-portfolio-type":[],"jetpack-portfolio-tag":[],"class_list":["post-1244","jetpack-portfolio","type-jetpack-portfolio","status-publish","format-standard","has-post-thumbnail","hentry"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":763,"url":"https:\/\/riptiderocks.nl\/index.php\/portfolio\/basisschool-de-schatgraver-landgraaf-19-08-2017\/","url_meta":{"origin":1244,"position":0},"title":"BASISSCHOOL DE SCHATGRAVER LANDGRAAF 19-08-2017","author":"Riptiderocks","date":"19 augustus, 2017","format":false,"excerpt":"","rel":"","context":"Soortgelijk bericht","block_context":{"text":"Soortgelijk bericht","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b1063.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b1063.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b1063.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b1063.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b1063.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":765,"url":"https:\/\/riptiderocks.nl\/index.php\/portfolio\/oefenbunker-landgraaf-biespop-battle-21-04-2017\/","url_meta":{"origin":1244,"position":1},"title":"OEFENBUNKER LANDGRAAF BIESPOP BATTLE 21-04-2017","author":"Riptiderocks","date":"21 april, 2017","format":false,"excerpt":"","rel":"","context":"Soortgelijk bericht","block_context":{"text":"Soortgelijk bericht","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b7246.jpg?fit=800%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b7246.jpg?fit=800%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b7246.jpg?fit=800%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b7246.jpg?fit=800%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":769,"url":"https:\/\/riptiderocks.nl\/index.php\/portfolio\/friends-family-try-out-oefenbunker-landgraaf-9-12-2017\/","url_meta":{"origin":1244,"position":2},"title":"FRIENDS &#038; FAMILY TRY-OUT OEFENBUNKER LANDGRAAF 9-12-2017","author":"Riptiderocks","date":"12 september, 2016","format":false,"excerpt":"","rel":"","context":"Soortgelijk bericht","block_context":{"text":"Soortgelijk bericht","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b5647.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b5647.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b5647.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b5647.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2018\/03\/6y8b5647.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1290,"url":"https:\/\/riptiderocks.nl\/index.php\/portfolio\/rockfabrik-open-air-2025\/","url_meta":{"origin":1244,"position":3},"title":"Rockfabrik Open Air 2025 5-9-2025","author":"Riptiderocks","date":"5 september, 2025","format":false,"excerpt":"","rel":"","context":"Soortgelijk bericht","block_context":{"text":"Soortgelijk bericht","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/544775552_1187926869810057_6712249075739597564_n.jpg?fit=1200%2C804&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/544775552_1187926869810057_6712249075739597564_n.jpg?fit=1200%2C804&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/544775552_1187926869810057_6712249075739597564_n.jpg?fit=1200%2C804&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/544775552_1187926869810057_6712249075739597564_n.jpg?fit=1200%2C804&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/544775552_1187926869810057_6712249075739597564_n.jpg?fit=1200%2C804&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1385,"url":"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-maneslust-6-9-2025\/","url_meta":{"origin":1244,"position":4},"title":"Caf\u00e9 Maneslust 6-9-2025","author":"Riptiderocks","date":"6 september, 2025","format":false,"excerpt":"","rel":"","context":"Soortgelijk bericht","block_context":{"text":"Soortgelijk bericht","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/09\/GRo-1W2A4278.jpg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1212,"url":"https:\/\/riptiderocks.nl\/index.php\/portfolio\/cafe-the-groove-sittard-5-4-2025\/","url_meta":{"origin":1244,"position":5},"title":"Caf\u00e9 The Groove Sittard 5-4-2025","author":"Riptiderocks","date":"8 april, 2025","format":false,"excerpt":"","rel":"","context":"Soortgelijk bericht","block_context":{"text":"Soortgelijk bericht","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/489284582_1194080382718048_7389646420476220897_n.jpg?fit=1200%2C960&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/489284582_1194080382718048_7389646420476220897_n.jpg?fit=1200%2C960&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/489284582_1194080382718048_7389646420476220897_n.jpg?fit=1200%2C960&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/489284582_1194080382718048_7389646420476220897_n.jpg?fit=1200%2C960&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/riptiderocks.nl\/wp-content\/uploads\/2025\/04\/489284582_1194080382718048_7389646420476220897_n.jpg?fit=1200%2C960&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/jetpack-portfolio\/1244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/jetpack-portfolio"}],"about":[{"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/types\/jetpack-portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/comments?post=1244"}],"version-history":[{"count":2,"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/jetpack-portfolio\/1244\/revisions"}],"predecessor-version":[{"id":1260,"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/jetpack-portfolio\/1244\/revisions\/1260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/media\/1236"}],"wp:attachment":[{"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/media?parent=1244"}],"wp:term":[{"taxonomy":"jetpack-portfolio-type","embeddable":true,"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/jetpack-portfolio-type?post=1244"},{"taxonomy":"jetpack-portfolio-tag","embeddable":true,"href":"https:\/\/riptiderocks.nl\/index.php\/wp-json\/wp\/v2\/jetpack-portfolio-tag?post=1244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}